{"id":5517,"date":"2023-02-24T07:00:00","date_gmt":"2023-02-24T07:00:00","guid":{"rendered":"http:\/\/maismagazine.pt\/?p=5517"},"modified":"2023-02-16T09:53:34","modified_gmt":"2023-02-16T09:53:34","slug":"e-um-orgulho-fazer-parte-da-festa","status":"publish","type":"post","link":"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/","title":{"rendered":"\u201c\u00c9 um orgulho fazer parte da Festa\u201d"},"content":{"rendered":"\n<p><strong>A cada quatro anos, centenas de pessoas assumem a tarefa de organizar a maior festividade do concelho de Tomar. A Festa dos Tabuleiros \u00e9 assim fruto do esp\u00edrito de trabalho, da vontade e da participa\u00e7\u00e3o de todos os tomarenses. Ant\u00f3nio Gra\u00e7a, Presidente da <a href=\"https:\/\/www.facebook.com\/FreguesiaSabacheira01\/\">Junta de Freguesia da Sabacheira<\/a>, \u00e9 testemunha da entrega e dedica\u00e7\u00e3o do seu povo \u00e0 \u201cFesta Maior\u201d.<\/strong><br><br>\u201cDo povo, feita pelo povo e para o povo\u201d, a Festa dos Tabuleiros \u00e9, acima de tudo, o s\u00edmbolo do esfor\u00e7o coletivo de todos os tomarenses em torno daquela que \u00e9 a \u201cFesta Maior\u201d da cidade templ\u00e1ria. Na Freguesia da Sabacheira, todos d\u00e3o o seu melhor para que tudo corra bem. Desde a prepara\u00e7\u00e3o das flores, que ir\u00e3o adornar as ruas da cidade \u00e0 produ\u00e7\u00e3o dos tabuleiros, passando ainda pela participa\u00e7\u00e3o nos jogos populares, no total mais de uma centena de pessoas est\u00e3o envolvidas na organiza\u00e7\u00e3o desta festividade secular. \u201c\u00c9 um orgulho fazer parte da Festa. Como indica o cognome, \u2018a Festa Maior\u2019, penso que explica o sentimento vivido por todos. \u00c9 a \u00e9poca em que remamos todos no mesmo sentido, em que o sentimento de perten\u00e7a encontra-se imbu\u00eddo em todos n\u00f3s e temos orgulho que cada momento, de cada trabalho\u201d, assume Ant\u00f3nio Gra\u00e7a, Presidente da Junta de Freguesia da Sabacheira.<br><br>Por esta altura, o esp\u00edrito de uni\u00e3o e de entreajuda invade todo o concelho. Na Sabacheira, \u201co per\u00edodo que vai desde o in\u00edcio da feitura das flores at\u00e9 ao dia seguinte ao cortejo maior, \u00e9 composto por momentos e viv\u00eancias \u00fanicas\u201d, que atingem o seu pin\u00e1culo com o arranque da festividade que este ano regressa \u00e0 cidade.<br><br>A Festa dos Tabuleiros \u00e9 verdadeiramente o ponto alto de todo o concelho de Tomar, mas n\u00e3o \u00e9 o \u00fanico pretexto para visitar a cidade templ\u00e1ria. \u201cNa Sabacheira temos todo o ano paisagens majestosas, com percursos pedestres e clic\u00e1veis \u00fanicos, onde as pessoas podem desfrutar de momentos de relaxamento, ou aventura na descida do Rio Nab\u00e3o, desde o Agroal at\u00e9 Tomar\u201d.<br><br><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/maismagazine.pt\/wp-content\/uploads\/2023\/02\/TMR-sabacheira-150x150.gif\" alt=\"\" class=\"wp-image-5518\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A cada quatro anos, centenas de pessoas assumem a tarefa de organizar a maior festividade do concelho de Tomar. A Festa dos Tabuleiros \u00e9 assim fruto do esp\u00edrito de trabalho, da vontade e da participa\u00e7\u00e3o de todos os tomarenses. Ant\u00f3nio Gra\u00e7a, Presidente da Junta de Freguesia da Sabacheira, \u00e9 testemunha&hellip;<\/p>\n","protected":false},"author":7,"featured_media":5519,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[9],"tags":[1260,1267],"class_list":["post-5517","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-festa-dos-tabuleiros","tag-sabacheira"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u201c\u00c9 um orgulho fazer parte da Festa\u201d - Mais Magazine<\/title>\n<meta name=\"description\" content=\"os \u00e9 assim fruto do esp\u00edrito de trabalho, da vontade e da participa\u00e7\u00e3o de todos os tomarenses. Ant\u00f3nio Gra\u00e7a, Presidente da Junta de Freguesia da Sabacheira, \u00e9 testemunha da entrega e dedica\u00e7\u00e3o do seu povo \u00e0 \u201cFesta Maior\u201d.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201c\u00c9 um orgulho fazer parte da Festa\u201d - Mais Magazine\" \/>\n<meta property=\"og:description\" content=\"os \u00e9 assim fruto do esp\u00edrito de trabalho, da vontade e da participa\u00e7\u00e3o de todos os tomarenses. Ant\u00f3nio Gra\u00e7a, Presidente da Junta de Freguesia da Sabacheira, \u00e9 testemunha da entrega e dedica\u00e7\u00e3o do seu povo \u00e0 \u201cFesta Maior\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/\" \/>\n<meta property=\"og:site_name\" content=\"Mais Magazine\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-24T07:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maismagazine.pt\/wp-content\/uploads\/2023\/02\/Grupo-FT2019.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"457\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jo\u00e3o Malainho\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/\"},\"author\":{\"name\":\"Jo\u00e3o Malainho\",\"@id\":\"http:\/\/maismagazine.pt\/#\/schema\/person\/999bd426f894ff56d397ec12ebd21ebb\"},\"headline\":\"\u201c\u00c9 um orgulho fazer parte da Festa\u201d\",\"datePublished\":\"2023-02-24T07:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/\"},\"wordCount\":353,\"publisher\":{\"@id\":\"http:\/\/maismagazine.pt\/#organization\"},\"image\":{\"@id\":\"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/maismagazine.pt\/wp-content\/uploads\/2023\/02\/Grupo-FT2019.jpg\",\"keywords\":[\"Festa dos Tabuleiros\",\"Sabacheira\"],\"articleSection\":[\"Cultura\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/\",\"url\":\"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/\",\"name\":\"\u201c\u00c9 um orgulho fazer parte da Festa\u201d - Mais Magazine\",\"isPartOf\":{\"@id\":\"http:\/\/maismagazine.pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/maismagazine.pt\/wp-content\/uploads\/2023\/02\/Grupo-FT2019.jpg\",\"datePublished\":\"2023-02-24T07:00:00+00:00\",\"description\":\"os \u00e9 assim fruto do esp\u00edrito de trabalho, da vontade e da participa\u00e7\u00e3o de todos os tomarenses. Ant\u00f3nio Gra\u00e7a, Presidente da Junta de Freguesia da Sabacheira, \u00e9 testemunha da entrega e dedica\u00e7\u00e3o do seu povo \u00e0 \u201cFesta Maior\u201d.\",\"breadcrumb\":{\"@id\":\"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/#primaryimage\",\"url\":\"https:\/\/maismagazine.pt\/wp-content\/uploads\/2023\/02\/Grupo-FT2019.jpg\",\"contentUrl\":\"https:\/\/maismagazine.pt\/wp-content\/uploads\/2023\/02\/Grupo-FT2019.jpg\",\"width\":1080,\"height\":457},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/maismagazine.pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201c\u00c9 um orgulho fazer parte da Festa\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/maismagazine.pt\/#website\",\"url\":\"http:\/\/maismagazine.pt\/\",\"name\":\"Mais Magazine\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\/\/maismagazine.pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/maismagazine.pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/maismagazine.pt\/#organization\",\"name\":\"Mais Magazine\",\"url\":\"http:\/\/maismagazine.pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"http:\/\/maismagazine.pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/maismagazine.pt\/wp-content\/uploads\/2020\/04\/cropped-cropped-mais-magazine-site-logo-2.png\",\"contentUrl\":\"https:\/\/maismagazine.pt\/wp-content\/uploads\/2020\/04\/cropped-cropped-mais-magazine-site-logo-2.png\",\"width\":581,\"height\":90,\"caption\":\"Mais Magazine\"},\"image\":{\"@id\":\"http:\/\/maismagazine.pt\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\/\/maismagazine.pt\/#\/schema\/person\/999bd426f894ff56d397ec12ebd21ebb\",\"name\":\"Jo\u00e3o Malainho\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"http:\/\/maismagazine.pt\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ff03c2f38edf60b2a827aa4f74878491?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ff03c2f38edf60b2a827aa4f74878491?s=96&d=mm&r=g\",\"caption\":\"Jo\u00e3o Malainho\"},\"url\":\"https:\/\/maismagazine.pt\/index.php\/author\/maismagazine\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201c\u00c9 um orgulho fazer parte da Festa\u201d - Mais Magazine","description":"os \u00e9 assim fruto do esp\u00edrito de trabalho, da vontade e da participa\u00e7\u00e3o de todos os tomarenses. Ant\u00f3nio Gra\u00e7a, Presidente da Junta de Freguesia da Sabacheira, \u00e9 testemunha da entrega e dedica\u00e7\u00e3o do seu povo \u00e0 \u201cFesta Maior\u201d.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/","og_locale":"pt_PT","og_type":"article","og_title":"\u201c\u00c9 um orgulho fazer parte da Festa\u201d - Mais Magazine","og_description":"os \u00e9 assim fruto do esp\u00edrito de trabalho, da vontade e da participa\u00e7\u00e3o de todos os tomarenses. Ant\u00f3nio Gra\u00e7a, Presidente da Junta de Freguesia da Sabacheira, \u00e9 testemunha da entrega e dedica\u00e7\u00e3o do seu povo \u00e0 \u201cFesta Maior\u201d.","og_url":"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/","og_site_name":"Mais Magazine","article_published_time":"2023-02-24T07:00:00+00:00","og_image":[{"width":1080,"height":457,"url":"https:\/\/maismagazine.pt\/wp-content\/uploads\/2023\/02\/Grupo-FT2019.jpg","type":"image\/jpeg"}],"author":"Jo\u00e3o Malainho","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":false,"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/#article","isPartOf":{"@id":"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/"},"author":{"name":"Jo\u00e3o Malainho","@id":"http:\/\/maismagazine.pt\/#\/schema\/person\/999bd426f894ff56d397ec12ebd21ebb"},"headline":"\u201c\u00c9 um orgulho fazer parte da Festa\u201d","datePublished":"2023-02-24T07:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/"},"wordCount":353,"publisher":{"@id":"http:\/\/maismagazine.pt\/#organization"},"image":{"@id":"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/#primaryimage"},"thumbnailUrl":"https:\/\/maismagazine.pt\/wp-content\/uploads\/2023\/02\/Grupo-FT2019.jpg","keywords":["Festa dos Tabuleiros","Sabacheira"],"articleSection":["Cultura"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/","url":"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/","name":"\u201c\u00c9 um orgulho fazer parte da Festa\u201d - Mais Magazine","isPartOf":{"@id":"http:\/\/maismagazine.pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/#primaryimage"},"image":{"@id":"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/#primaryimage"},"thumbnailUrl":"https:\/\/maismagazine.pt\/wp-content\/uploads\/2023\/02\/Grupo-FT2019.jpg","datePublished":"2023-02-24T07:00:00+00:00","description":"os \u00e9 assim fruto do esp\u00edrito de trabalho, da vontade e da participa\u00e7\u00e3o de todos os tomarenses. Ant\u00f3nio Gra\u00e7a, Presidente da Junta de Freguesia da Sabacheira, \u00e9 testemunha da entrega e dedica\u00e7\u00e3o do seu povo \u00e0 \u201cFesta Maior\u201d.","breadcrumb":{"@id":"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/#primaryimage","url":"https:\/\/maismagazine.pt\/wp-content\/uploads\/2023\/02\/Grupo-FT2019.jpg","contentUrl":"https:\/\/maismagazine.pt\/wp-content\/uploads\/2023\/02\/Grupo-FT2019.jpg","width":1080,"height":457},{"@type":"BreadcrumbList","@id":"https:\/\/maismagazine.pt\/index.php\/2023\/02\/24\/e-um-orgulho-fazer-parte-da-festa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/maismagazine.pt\/"},{"@type":"ListItem","position":2,"name":"\u201c\u00c9 um orgulho fazer parte da Festa\u201d"}]},{"@type":"WebSite","@id":"http:\/\/maismagazine.pt\/#website","url":"http:\/\/maismagazine.pt\/","name":"Mais Magazine","description":"","publisher":{"@id":"http:\/\/maismagazine.pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/maismagazine.pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"http:\/\/maismagazine.pt\/#organization","name":"Mais Magazine","url":"http:\/\/maismagazine.pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"http:\/\/maismagazine.pt\/#\/schema\/logo\/image\/","url":"https:\/\/maismagazine.pt\/wp-content\/uploads\/2020\/04\/cropped-cropped-mais-magazine-site-logo-2.png","contentUrl":"https:\/\/maismagazine.pt\/wp-content\/uploads\/2020\/04\/cropped-cropped-mais-magazine-site-logo-2.png","width":581,"height":90,"caption":"Mais Magazine"},"image":{"@id":"http:\/\/maismagazine.pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/maismagazine.pt\/#\/schema\/person\/999bd426f894ff56d397ec12ebd21ebb","name":"Jo\u00e3o Malainho","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"http:\/\/maismagazine.pt\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ff03c2f38edf60b2a827aa4f74878491?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff03c2f38edf60b2a827aa4f74878491?s=96&d=mm&r=g","caption":"Jo\u00e3o Malainho"},"url":"https:\/\/maismagazine.pt\/index.php\/author\/maismagazine\/"}]}},"author_meta":{"display_name":false,"author_link":"https:\/\/maismagazine.pt\/index.php\/author\/maismagazine\/"},"featured_img":"https:\/\/maismagazine.pt\/wp-content\/uploads\/2023\/02\/Grupo-FT2019-300x127.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/maismagazine.pt\/index.php\/category\/cultura\/\" class=\"advgb-post-tax-term\">Cultura<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Cultura<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/maismagazine.pt\/index.php\/category\/cultura\/\" class=\"advgb-post-tax-term\">Festa dos Tabuleiros<\/a>","<a href=\"https:\/\/maismagazine.pt\/index.php\/category\/cultura\/\" class=\"advgb-post-tax-term\">Sabacheira<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Festa dos Tabuleiros<\/span>","<span class=\"advgb-post-tax-term\">Sabacheira<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Posted 3 anos ago","modified":"Updated 3 anos ago"},"absolute_dates":{"created":"Posted on 24 de Fevereiro, 2023","modified":"Updated on 16 de Fevereiro, 2023"},"absolute_dates_time":{"created":"Posted on 24 de Fevereiro, 2023 7:00","modified":"Updated on 16 de Fevereiro, 2023 9:53"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/maismagazine.pt\/index.php\/wp-json\/wp\/v2\/posts\/5517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maismagazine.pt\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maismagazine.pt\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maismagazine.pt\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/maismagazine.pt\/index.php\/wp-json\/wp\/v2\/comments?post=5517"}],"version-history":[{"count":2,"href":"https:\/\/maismagazine.pt\/index.php\/wp-json\/wp\/v2\/posts\/5517\/revisions"}],"predecessor-version":[{"id":5671,"href":"https:\/\/maismagazine.pt\/index.php\/wp-json\/wp\/v2\/posts\/5517\/revisions\/5671"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maismagazine.pt\/index.php\/wp-json\/wp\/v2\/media\/5519"}],"wp:attachment":[{"href":"https:\/\/maismagazine.pt\/index.php\/wp-json\/wp\/v2\/media?parent=5517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maismagazine.pt\/index.php\/wp-json\/wp\/v2\/categories?post=5517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maismagazine.pt\/index.php\/wp-json\/wp\/v2\/tags?post=5517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}